{"id":3196,"count":1,"description":"","link":"https:\/\/www.ssww.com\/blog\/tag\/descriptive-sentences\/","name":"descriptive sentences","slug":"descriptive-sentences","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>descriptive sentences Archives - S&amp;S Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"descriptive sentences Archives - S&amp;S Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ssww.com\/blog\/tag\/descriptive-sentences\/\" \/>\n<meta property=\"og:site_name\" content=\"S&amp;S Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ssworldwide\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ssww.com\/blog\/#website\",\"url\":\"https:\/\/www.ssww.com\/blog\/\",\"name\":\"S&amp;S Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ssww.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.ssww.com\/blog\/tag\/descriptive-sentences\/#webpage\",\"url\":\"https:\/\/www.ssww.com\/blog\/tag\/descriptive-sentences\/\",\"name\":\"descriptive sentences Archives - S&amp;S Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.ssww.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ssww.com\/blog\/tag\/descriptive-sentences\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ssww.com\/blog\/tag\/descriptive-sentences\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ssww.com\/blog\/tag\/descriptive-sentences\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ssww.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"descriptive sentences\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"descriptive sentences Archives - S&amp;S Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"descriptive sentences Archives - S&amp;S Blog","og_url":"https:\/\/www.ssww.com\/blog\/tag\/descriptive-sentences\/","og_site_name":"S&amp;S Blog","twitter_card":"summary_large_image","twitter_site":"@ssworldwide","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.ssww.com\/blog\/#website","url":"https:\/\/www.ssww.com\/blog\/","name":"S&amp;S Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ssww.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"CollectionPage","@id":"https:\/\/www.ssww.com\/blog\/tag\/descriptive-sentences\/#webpage","url":"https:\/\/www.ssww.com\/blog\/tag\/descriptive-sentences\/","name":"descriptive sentences Archives - S&amp;S Blog","isPartOf":{"@id":"https:\/\/www.ssww.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.ssww.com\/blog\/tag\/descriptive-sentences\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ssww.com\/blog\/tag\/descriptive-sentences\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ssww.com\/blog\/tag\/descriptive-sentences\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ssww.com\/blog\/"},{"@type":"ListItem","position":2,"name":"descriptive sentences"}]}]}},"_links":{"self":[{"href":"https:\/\/www.ssww.com\/blog\/wp-json\/wp\/v2\/tags\/3196"}],"collection":[{"href":"https:\/\/www.ssww.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.ssww.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.ssww.com\/blog\/wp-json\/wp\/v2\/posts?tags=3196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}